{"id":35622,"date":"2026-01-28T17:35:16","date_gmt":"2026-01-28T16:35:16","guid":{"rendered":"https:\/\/www.e20srl.com\/?post_type=product&#038;p=35622"},"modified":"2026-02-03T15:18:05","modified_gmt":"2026-02-03T14:18:05","slug":"luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad","status":"publish","type":"product","link":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/","title":{"rendered":"Luca Viterbo Donato &#8211; La gestione dello studio attraverso lo smartphone 2026 &#8211; FAD"},"content":{"rendered":"<h5 style=\"color: #2e3192;\"><strong>ABSTRACT<\/strong><\/h5>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-35623 \" src=\"https:\/\/www.e20srl.com\/wp-content\/uploads\/2026\/01\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg\" alt=\"\" width=\"343\" height=\"343\" \/><\/p>\n<p class=\"column\">Sempre di pi\u00f9 siamo portati a utilizzare lo smartphone in ambito professionale.<br \/>\nIl problema principale che la maggior parte delle persone, per mancanza di formazione, utilizza solo il 15% delle risorse dello stesso.<br \/>\nIl corso vi permetter\u00e0 attraverso gli esercizi pratici di utilizzare lo smartphone nel pieno complesso delle sue potenzialit\u00e0.<br \/>\nL\u2019acquisizione di questa nuova conoscenza vi faciliter\u00e0 non solo in ambito lavorativo (un mondo sempre pi\u00f9 connesso) ma anche nella vita privata di tutti i giorni.<\/p>\n<p>&nbsp;<\/p>\n<h5><\/h5>\n<h5 style=\"color: #2e3192;\"><strong>PROGRAMMA DEL CORSO<\/strong><\/h5>\n<ul>\n<li>Concetti base<\/li>\n<li>Analisi del menu<\/li>\n<li>La fotografia e video in odontoiatria<\/li>\n<li>L\u2019archiviazione dei dati: il cloud<\/li>\n<li>Il rispetto della privacy<\/li>\n<li>La connessione internet<\/li>\n<li>La domotica nello studio odontoiatrico<\/li>\n<li>La comunicazione con i pazienti<\/li>\n<li>La gestione dei social<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5 style=\"color: #2e3192;\"><strong>DESTINATARI DEL CORSO<\/strong><\/h5>\n<p>Figure professionali : A.S.O.<\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"color: #2e3192;\"><strong>MODALITA\u2019 DI SVOLGIMENTO<\/strong><\/h5>\n<p>Le attivit\u00e0 si svolgeranno\u00a0<strong>in FAD<\/strong>.<\/p>\n<table style=\"border-collapse: collapse; width: 99.9203%; height: 103px;\">\n<tbody>\n<tr style=\"background-color: #cfebfe;\">\n<td style=\"width: 100%; text-align: left;\">Per coloro che hanno scelto il pagamento tramite bonifico bancario, si informa che essendo un corso pratico con posti limitati, l\u2019iscrizione sar\u00e0 considerata valida se seguita entro 5gg. dalla prenotazione, dalla contabile del pagamento. Diversamente, la prenotazione sar\u00e0 automaticamente cancellata.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h5 style=\"color: #2e3192;\"><strong>POLICY DI CANCELLAZIONE<\/strong><\/h5>\n<p class=\"column\">In caso di mancata partecipazione verr\u00e0 effettuato un rimborso al netto dei diritti di Segreteria (50% della quota di iscrizione iva compresa) solo se la disdetta scritta sar\u00e0 pervenuta alla Segreteria entro e non oltre 15 giorni lavorativi prima dallo svolgimento dell\u2019evento per comprovati motivi. Le iscrizioni saranno ritenute valide solo se accompagnate dalla quota di iscrizione o dalla ricevuta del bonifico.<\/p>\n","protected":false},"excerpt":{"rendered":"<h5>10 ORE DI AGGIORNAMENTO<\/h5>\n<h5><span style=\"color: #2e3192;\">Quota di iscrizione: <\/span><span style=\"color: #2e3192;\"><strong>\u20ac 40,00 + IVA (22%)<\/strong><\/span><\/h5>\n<p><a href=\"https:\/\/www.e20srl.com\/area-privata\/index.php?id=2562&amp;iscrizione=1\"><img decoding=\"async\" class=\"alignnone wp-image-22052 size-full\" src=\"https:\/\/www.e20srl.com\/wp-content\/uploads\/2023\/10\/pulsante-acquista.png\" alt=\"pulsante acquista\" width=\"395\" height=\"72\" \/><\/a><\/p>\n","protected":false},"featured_media":35623,"menu_order":137,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[605,644],"product_tag":[656],"class_list":{"0":"post-35622","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-a-s-o","7":"product_cat-fad","8":"product_tag-fad","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luca Viterbo Donato - La gestione dello studio attraverso lo smartphone 2026 - FAD | e20<\/title>\n<meta name=\"description\" content=\"Il corso vi permetter\u00e0 attraverso gli esercizi pratici di utilizzare lo smartphone nel pieno complesso delle sue potenzialit\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luca Viterbo Donato - La gestione dello studio attraverso lo smartphone 2026 - FAD | e20\" \/>\n<meta property=\"og:description\" content=\"Il corso vi permetter\u00e0 attraverso gli esercizi pratici di utilizzare lo smartphone nel pieno complesso delle sue potenzialit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/\" \/>\n<meta property=\"og:site_name\" content=\"e20\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/e20srl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T14:18:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.e20srl.com\/wp-content\/uploads\/2026\/01\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"2480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/prodotti\\\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\\\/\",\"url\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/prodotti\\\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\\\/\",\"name\":\"Luca Viterbo Donato - La gestione dello studio attraverso lo smartphone 2026 - FAD | e20\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/prodotti\\\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/prodotti\\\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e20srl.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg\",\"datePublished\":\"2026-01-28T16:35:16+00:00\",\"dateModified\":\"2026-02-03T14:18:05+00:00\",\"description\":\"Il corso vi permetter\u00e0 attraverso gli esercizi pratici di utilizzare lo smartphone nel pieno complesso delle sue potenzialit\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/prodotti\\\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.e20srl.com\\\/en\\\/prodotti\\\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/prodotti\\\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.e20srl.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.e20srl.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg\",\"width\":2480,\"height\":2480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/prodotti\\\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luca Viterbo Donato &#8211; La gestione dello studio attraverso lo smartphone 2026 &#8211; FAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/\",\"name\":\"e20\",\"description\":\"Congressi e Corsi in presenza, FAD, webinar di Eccellenza per Odontoiatra, Igienista dentale, ASO\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/#organization\",\"name\":\"e20 s.r.l.\",\"url\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.e20srl.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/e20-icona.png\",\"contentUrl\":\"https:\\\/\\\/www.e20srl.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/e20-icona.png\",\"width\":512,\"height\":512,\"caption\":\"e20 s.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e20srl.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/e20srl\",\"https:\\\/\\\/www.instagram.com\\\/e20.srl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCFK9MwMuURf-lxw-ca0PNHw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/e20-srl\\\/about\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luca Viterbo Donato - La gestione dello studio attraverso lo smartphone 2026 - FAD | e20","description":"Il corso vi permetter\u00e0 attraverso gli esercizi pratici di utilizzare lo smartphone nel pieno complesso delle sue potenzialit\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/","og_locale":"en_US","og_type":"article","og_title":"Luca Viterbo Donato - La gestione dello studio attraverso lo smartphone 2026 - FAD | e20","og_description":"Il corso vi permetter\u00e0 attraverso gli esercizi pratici di utilizzare lo smartphone nel pieno complesso delle sue potenzialit\u00e0.","og_url":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/","og_site_name":"e20","article_publisher":"https:\/\/www.facebook.com\/e20srl","article_modified_time":"2026-02-03T14:18:05+00:00","og_image":[{"width":2480,"height":2480,"url":"https:\/\/www.e20srl.com\/wp-content\/uploads\/2026\/01\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/","url":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/","name":"Luca Viterbo Donato - La gestione dello studio attraverso lo smartphone 2026 - FAD | e20","isPartOf":{"@id":"https:\/\/www.e20srl.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/#primaryimage"},"image":{"@id":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e20srl.com\/wp-content\/uploads\/2026\/01\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg","datePublished":"2026-01-28T16:35:16+00:00","dateModified":"2026-02-03T14:18:05+00:00","description":"Il corso vi permetter\u00e0 attraverso gli esercizi pratici di utilizzare lo smartphone nel pieno complesso delle sue potenzialit\u00e0.","breadcrumb":{"@id":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/#primaryimage","url":"https:\/\/www.e20srl.com\/wp-content\/uploads\/2026\/01\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg","contentUrl":"https:\/\/www.e20srl.com\/wp-content\/uploads\/2026\/01\/FAD-2026-ASO-Gestione-dello-studio-attraverso-lo-smartphone-Donato-rev.1.jpg","width":2480,"height":2480},{"@type":"BreadcrumbList","@id":"https:\/\/www.e20srl.com\/en\/prodotti\/luca-viterbo-donato-la-gestione-dello-studio-attraverso-lo-smartphone-2026-fad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.e20srl.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.e20srl.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Luca Viterbo Donato &#8211; La gestione dello studio attraverso lo smartphone 2026 &#8211; FAD"}]},{"@type":"WebSite","@id":"https:\/\/www.e20srl.com\/en\/#website","url":"https:\/\/www.e20srl.com\/en\/","name":"e20","description":"Congressi e Corsi in presenza, FAD, webinar di Eccellenza per Odontoiatra, Igienista dentale, ASO","publisher":{"@id":"https:\/\/www.e20srl.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e20srl.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.e20srl.com\/en\/#organization","name":"e20 s.r.l.","url":"https:\/\/www.e20srl.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.e20srl.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.e20srl.com\/wp-content\/uploads\/2022\/10\/e20-icona.png","contentUrl":"https:\/\/www.e20srl.com\/wp-content\/uploads\/2022\/10\/e20-icona.png","width":512,"height":512,"caption":"e20 s.r.l."},"image":{"@id":"https:\/\/www.e20srl.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/e20srl","https:\/\/www.instagram.com\/e20.srl\/","https:\/\/www.youtube.com\/channel\/UCFK9MwMuURf-lxw-ca0PNHw","https:\/\/www.linkedin.com\/company\/e20-srl\/about\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.e20srl.com\/en\/wp-json\/wp\/v2\/product\/35622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e20srl.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.e20srl.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.e20srl.com\/en\/wp-json\/wp\/v2\/media\/35623"}],"wp:attachment":[{"href":"https:\/\/www.e20srl.com\/en\/wp-json\/wp\/v2\/media?parent=35622"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.e20srl.com\/en\/wp-json\/wp\/v2\/product_brand?post=35622"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.e20srl.com\/en\/wp-json\/wp\/v2\/product_cat?post=35622"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.e20srl.com\/en\/wp-json\/wp\/v2\/product_tag?post=35622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}